{"id":75548,"date":"2026-09-02T13:47:11","date_gmt":"2026-09-02T17:47:11","guid":{"rendered":"https:\/\/munilaja.cl\/w\/?p=75548"},"modified":"2026-09-02T13:47:12","modified_gmt":"2026-09-02T17:47:12","slug":"resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026","status":"publish","type":"post","link":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/","title":{"rendered":"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026"},"content":{"rendered":"\n<p>La Municipalidad de Laja informa a la comunidad y a todos los participantes que ya se encuentran disponibles los resultados oficiales del proceso de postulaci\u00f3n para las actividades y espacios de <strong>Vive las Fiestas Patrias 2026<\/strong>.<\/p>\n\n\n\n<p>Agradecemos el gran inter\u00e9s y compromiso de cada uno de los postulantes por ser parte de estas celebraciones tradicionales.<\/p>\n\n\n\n<p>Revisa la n\u00f3mina de seleccionados en el siguiente listado:<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\"  class=\"wp-block-file__embed\" data=\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/LISTA-DE-SELECCIONADOS-FIESTAS-PATRIAS-2026-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de LISTA DE SELECCIONADOS FIESTAS PATRIAS 2026 (1).\"><\/object><a id=\"wp-block-file--media-1aa413d7-4ee8-4a4b-a3ce-483b0cebf820\" href=\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/LISTA-DE-SELECCIONADOS-FIESTAS-PATRIAS-2026-1.pdf\">LISTA DE SELECCIONADOS FIESTAS PATRIAS 2026 (1)<\/a><a href=\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/LISTA-DE-SELECCIONADOS-FIESTAS-PATRIAS-2026-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1aa413d7-4ee8-4a4b-a3ce-483b0cebf820\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Laja informa a la comunidad y a todos los participantes que ya se encuentran disponibles los resultados oficiales del proceso de postulaci\u00f3n para las actividades y espacios de Vive las Fiestas Patrias 2026. Agradecemos el gran inter\u00e9s y compromiso de cada uno de los postulantes por ser parte de estas celebraciones tradicionales. [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":75550,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"zakra_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"zakra_menu_active_style","zakra_page_header":true,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-75548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicio-a-la-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026 - Municipalidad de Laja<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026 - Municipalidad de Laja\" \/>\n<meta property=\"og:description\" content=\"La Municipalidad de Laja informa a la comunidad y a todos los participantes que ya se encuentran disponibles los resultados oficiales del proceso de postulaci\u00f3n para las actividades y espacios de Vive las Fiestas Patrias 2026. Agradecemos el gran inter\u00e9s y compromiso de cada uno de los postulantes por ser parte de estas celebraciones tradicionales. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Municipalidad de Laja\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T17:47:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T17:47:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristian Matamala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristian Matamala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\"},\"author\":{\"name\":\"Cristian Matamala\",\"@id\":\"https:\/\/munilaja.cl\/w\/#\/schema\/person\/a167620fc64f5320fb5c3983b8cdbf8f\"},\"headline\":\"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026\",\"datePublished\":\"2026-09-02T17:47:11+00:00\",\"dateModified\":\"2026-09-02T17:47:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\/\/munilaja.cl\/w\/#organization\"},\"image\":{\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg\",\"articleSection\":[\"Servicio a la comunidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\",\"url\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\",\"name\":\"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026 - Municipalidad de Laja\",\"isPartOf\":{\"@id\":\"https:\/\/munilaja.cl\/w\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg\",\"datePublished\":\"2026-09-02T17:47:11+00:00\",\"dateModified\":\"2026-09-02T17:47:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage\",\"url\":\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg\",\"contentUrl\":\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/munilaja.cl\/w\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/munilaja.cl\/w\/#website\",\"url\":\"https:\/\/munilaja.cl\/w\/\",\"name\":\"Municipalidad de Laja\",\"description\":\"Web Municipal\",\"publisher\":{\"@id\":\"https:\/\/munilaja.cl\/w\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/munilaja.cl\/w\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/munilaja.cl\/w\/#organization\",\"name\":\"Municipalidad de Laja\",\"url\":\"https:\/\/munilaja.cl\/w\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/munilaja.cl\/w\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2024\/11\/ESCUDO-LAJA-LETRAS-BLANCAS-LOGO-WEB.png\",\"contentUrl\":\"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2024\/11\/ESCUDO-LAJA-LETRAS-BLANCAS-LOGO-WEB.png\",\"width\":150,\"height\":150,\"caption\":\"Municipalidad de Laja\"},\"image\":{\"@id\":\"https:\/\/munilaja.cl\/w\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/munilaja.cl\/w\/#\/schema\/person\/a167620fc64f5320fb5c3983b8cdbf8f\",\"name\":\"Cristian Matamala\",\"url\":\"https:\/\/munilaja.cl\/w\/author\/cmatamala\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026 - Municipalidad de Laja","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026 - Municipalidad de Laja","og_description":"La Municipalidad de Laja informa a la comunidad y a todos los participantes que ya se encuentran disponibles los resultados oficiales del proceso de postulaci\u00f3n para las actividades y espacios de Vive las Fiestas Patrias 2026. Agradecemos el gran inter\u00e9s y compromiso de cada uno de los postulantes por ser parte de estas celebraciones tradicionales. [&hellip;]","og_url":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/","og_site_name":"Municipalidad de Laja","article_published_time":"2026-09-02T17:47:11+00:00","article_modified_time":"2026-09-02T17:47:12+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg","type":"image\/jpeg"}],"author":"Cristian Matamala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cristian Matamala","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#article","isPartOf":{"@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/"},"author":{"name":"Cristian Matamala","@id":"https:\/\/munilaja.cl\/w\/#\/schema\/person\/a167620fc64f5320fb5c3983b8cdbf8f"},"headline":"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026","datePublished":"2026-09-02T17:47:11+00:00","dateModified":"2026-09-02T17:47:12+00:00","mainEntityOfPage":{"@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/"},"wordCount":80,"publisher":{"@id":"https:\/\/munilaja.cl\/w\/#organization"},"image":{"@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg","articleSection":["Servicio a la comunidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/","url":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/","name":"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026 - Municipalidad de Laja","isPartOf":{"@id":"https:\/\/munilaja.cl\/w\/#website"},"primaryImageOfPage":{"@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage"},"image":{"@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg","datePublished":"2026-09-02T17:47:11+00:00","dateModified":"2026-09-02T17:47:12+00:00","breadcrumb":{"@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#primaryimage","url":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg","contentUrl":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2026\/09\/resultados-postunlaciones.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/munilaja.cl\/w\/resultados-de-postulaciones-vive-las-fiestas-patrias-laja-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/munilaja.cl\/w\/"},{"@type":"ListItem","position":2,"name":"Resultados de postulaciones: Vive las Fiestas Patrias Laja 2026"}]},{"@type":"WebSite","@id":"https:\/\/munilaja.cl\/w\/#website","url":"https:\/\/munilaja.cl\/w\/","name":"Municipalidad de Laja","description":"Web Municipal","publisher":{"@id":"https:\/\/munilaja.cl\/w\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/munilaja.cl\/w\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/munilaja.cl\/w\/#organization","name":"Municipalidad de Laja","url":"https:\/\/munilaja.cl\/w\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/munilaja.cl\/w\/#\/schema\/logo\/image\/","url":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2024\/11\/ESCUDO-LAJA-LETRAS-BLANCAS-LOGO-WEB.png","contentUrl":"https:\/\/munilaja.cl\/w\/wp-content\/uploads\/2024\/11\/ESCUDO-LAJA-LETRAS-BLANCAS-LOGO-WEB.png","width":150,"height":150,"caption":"Municipalidad de Laja"},"image":{"@id":"https:\/\/munilaja.cl\/w\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/munilaja.cl\/w\/#\/schema\/person\/a167620fc64f5320fb5c3983b8cdbf8f","name":"Cristian Matamala","url":"https:\/\/munilaja.cl\/w\/author\/cmatamala\/"}]}},"_links":{"self":[{"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/posts\/75548"}],"collection":[{"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/comments?post=75548"}],"version-history":[{"count":1,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/posts\/75548\/revisions"}],"predecessor-version":[{"id":75551,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/posts\/75548\/revisions\/75551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/media\/75550"}],"wp:attachment":[{"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/media?parent=75548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/categories?post=75548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/munilaja.cl\/w\/wp-json\/wp\/v2\/tags?post=75548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}